{"id":1284,"date":"2021-06-10T20:38:34","date_gmt":"2021-06-10T18:38:34","guid":{"rendered":"https:\/\/www.sfoglie.ch\/minestra-di-fagioli-di-lamon-igp-con-sfoglie-di-polenta\/"},"modified":"2021-07-02T14:54:55","modified_gmt":"2021-07-02T12:54:55","slug":"lamon-bohnensuppe-igp-mit-polenta-chips","status":"publish","type":"post","link":"https:\/\/www.sfoglie.ch\/de\/lamon-bohnensuppe-igp-mit-polenta-chips\/","title":{"rendered":"Lamon Bohnensuppe IGP mit Polenta Chips"},"content":{"rendered":"\n<p>(Rezept aus dem Blog <a rel=\"noreferrer noopener\" href=\"https:\/\/www.youtube.com\/channel\/UCbplKPUQjxIJYIgmhHVgyBw\" target=\"_blank\">Delights and Flavours of Denise<\/a>)<\/p>\n\n\n\n<p><strong><strong>Zutaten<\/strong>:<br><\/strong>\u2013 500 g getrocknete Bohnen von Lamon<br>\u2013 100 g Eierbandnudeln<br>\u2013 250 g Schinkenspeck von Norcia<br>\u2013 1 Zwiebel<br>\u2013 1 Knoblauchzehe<br>\u2013 3 l\u00f6ffeln Petersilie zerkleinert<br>\u2013 3 l\u00f6ffeln Tomatenmark<br>\u2013 \u215f\u2084 Gl\u00e4ser Weisswein<br>\u2013 EVO-\u00d6l<br>\u2013 Gem\u00fcsebr\u00fche oder Fleischbr\u00fche<br>\u2013 Polenta Chips<br>\u2013 Pfeffer<br>\u2013 Salz<\/p>\n\n\n\n<p><strong><strong><strong>Zubereitung<\/strong><\/strong>:<br><\/strong>Die Bohnen 12 Stunden lang einweichen. Am Ende abtropfen lassen und 40 Minuten lang in reichlich Salzwasser kochen, danach abtropfen lassen und beiseitestellen.<br>Die Zwiebel fein schneiden, den Knoblauch sch\u00e4len und in einem grossen Topf mit reichlich extra nativem Oliven\u00f6l anbraten.<br>Den Speck ohne Schwarte in W\u00fcrfel schneiden knusprig braten, ab und zu mit Weisswein abl\u00f6schen.<br>Den Knoblauch entfernen und die passierten Tomaten und die Petersilie dazugeben.<br>Die Bohnen halbieren. Eine H\u00e4lfte mit Hilfe eines Mixers zu P\u00fcree zerkleinern und zusammen mit etwas Br\u00fche in die Kasserolle gegeben. Die andere H\u00e4lfte beiseitelegen.<br>Jetzt k\u00f6nnen Sie die Schweineschwarte des Specks hinzuf\u00fcgen, damit der Geschmack intensiver wird. Bei schwacher Hitze 30-40 Minuten kochen lassen und ab und zu Br\u00fche hinzugiessen, um ein zu starkes Schrumpfen zu verhindern. Zusammen mit den Polenta Chips servieren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Rezept aus dem Blog Delights and Flavours of Denise) Zutaten:\u2013 500 g getrocknete Bohnen von Lamon\u2013 100 g Eierbandnudeln\u2013 250 g Schinkenspeck von Norcia\u2013 1 Zwiebel\u2013 1 Knoblauchzehe\u2013 3 l\u00f6ffeln Petersilie zerkleinert\u2013 3 l\u00f6ffeln Tomatenmark\u2013 \u215f\u2084 Gl\u00e4ser Weisswein\u2013 EVO-\u00d6l\u2013 Gem\u00fcsebr\u00fche oder Fleischbr\u00fche\u2013 Polenta Chips\u2013 Pfeffer\u2013 Salz Zubereitung:Die Bohnen 12 Stunden lang einweichen. Am Ende abtropfen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1285,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-1284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezepte"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/posts\/1284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/comments?post=1284"}],"version-history":[{"count":2,"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/posts\/1284\/revisions"}],"predecessor-version":[{"id":1506,"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/posts\/1284\/revisions\/1506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/media\/1285"}],"wp:attachment":[{"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/media?parent=1284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/categories?post=1284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sfoglie.ch\/de\/wp-json\/wp\/v2\/tags?post=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}